{"id":9841,"date":"2023-04-14T09:18:15","date_gmt":"2023-04-14T12:18:15","guid":{"rendered":"https:\/\/2022.aniu.org.uy\/all-documents\/"},"modified":"2023-05-05T16:39:05","modified_gmt":"2023-05-05T19:39:05","slug":"all-documents","status":"publish","type":"page","link":"https:\/\/aniu.org.uy\/en\/all-documents\/","title":{"rendered":"All documents"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9841\" class=\"elementor elementor-9841 elementor-8975\">\n\t\t\t\t\t\t<div class=\" elementor-section elementor-top-section elementor-element elementor-element-13c70aa elementor-section-full_width overflow-hidden alpha-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"13c70aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\r\n\t\t\t\t\t\t\t\t<!-- Begin .elementor-container -->\r\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no  banner banner-fixed \">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<figure class=\"banner-img\">\r\n\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"970\" src=\"https:\/\/aniu.org.uy\/wp-content\/uploads\/2023\/05\/banner-todos-documentos-1.jpg\" class=\"attachment-full size-full\" alt=\"\" style=\"background-color:#333333\" srcset=\"https:\/\/aniu.org.uy\/wp-content\/uploads\/2023\/05\/banner-todos-documentos-1.jpg 1920w, https:\/\/aniu.org.uy\/wp-content\/uploads\/2023\/05\/banner-todos-documentos-1-1024x517.jpg 1024w, https:\/\/aniu.org.uy\/wp-content\/uploads\/2023\/05\/banner-todos-documentos-1-768x388.jpg 768w, https:\/\/aniu.org.uy\/wp-content\/uploads\/2023\/05\/banner-todos-documentos-1-1536x776.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t<\/figure>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\" banner-content t-mc elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ec4d94 elementor-invisible \" data-id=\"8ec4d94\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44d607b elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"44d607b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDownShorter&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Todos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dec9c82 ms-auto me-auto elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dec9c82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDownShorter&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">All documents<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div><!-- End .elementor-container -->\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-999ff04 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"999ff04\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a01f23 \" data-id=\"2a01f23\" data-element_type=\"column\" data-e-type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ff7e8f elementor-widget elementor-widget-udesign_widget_breadcrumb\" data-id=\"4ff7e8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"udesign_widget_breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ol class=\"breadcrumb\"><li><a href=\"https:\/\/aniu.org.uy\/en\/\" aria-label=\"Breadcrumb\">Home<\/a><\/li><\/ol><script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\\\/\",\"@type\":\"BreadcrumbList\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"name\":\"Home\",\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/\"}}]}<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-e38990c alpha-section-stretched breadcrumb-wrap elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e38990c\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67e37f9 \" data-id=\"67e37f9\" data-element_type=\"column\" data-e-type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-a4892bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4892bc\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6bc09ea \" data-id=\"6bc09ea\" data-element_type=\"column\" data-e-type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8b19d8 elementor-widget elementor-widget-spacer\" data-id=\"a8b19d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-867c167 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"867c167\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-202fd38 \" data-id=\"202fd38\" data-element_type=\"column\" data-e-type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21f0f7f elementor-widget elementor-widget-udesign_widget_posts_grid\" data-id=\"21f0f7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"udesign_widget_posts_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"alpha-posts-grid-6305\" class=\"alpha-posts-grid\"><div class=\"alpha-posts-grid-container post-grid-udesign_portfolio gallery-popup-container posts portfolios row cols-lg-3 cols-md-3 cols-sm-2 cols-2 cols-xl-3\" data-load=\"{&quot;props&quot;:{&quot;shortcode_type&quot;:&quot;&quot;,&quot;shortcode&quot;:&quot;alpha-posts-grid&quot;,&quot;builder_id&quot;:&quot;&quot;,&quot;list_builder_id&quot;:&quot;&quot;,&quot;source&quot;:&quot;&quot;,&quot;post_type&quot;:&quot;udesign_portfolio&quot;,&quot;product_status&quot;:null,&quot;post_tax&quot;:&quot;udesign_portfolio_category&quot;,&quot;post_terms&quot;:[&quot;65&quot;,&quot;35&quot;,&quot;56&quot;],&quot;tax&quot;:null,&quot;terms&quot;:null,&quot;count&quot;:6,&quot;hide_empty&quot;:null,&quot;orderby&quot;:&quot;date&quot;,&quot;orderby_term&quot;:null,&quot;orderway&quot;:&quot;DESC&quot;,&quot;cats&quot;:&quot;&quot;,&quot;view&quot;:&quot;grid&quot;,&quot;row_cnt&quot;:1,&quot;col_cnt&quot;:&quot;3&quot;,&quot;col_cnt_xl&quot;:&quot;3&quot;,&quot;col_cnt_tablet&quot;:&quot;&quot;,&quot;col_cnt_mobile&quot;:&quot;&quot;,&quot;col_cnt_min&quot;:&quot;&quot;,&quot;list_col_cnt&quot;:&quot;&quot;,&quot;col_sp&quot;:&quot;&quot;,&quot;creative_cols&quot;:null,&quot;creative_cols_tablet&quot;:&quot;&quot;,&quot;creative_cols_mobile&quot;:&quot;&quot;,&quot;items_list&quot;:null,&quot;loadmore_type&quot;:&quot;button&quot;,&quot;loadmore_label&quot;:&quot;Load more&quot;,&quot;filter_cat_w&quot;:&quot;&quot;,&quot;filter_cat&quot;:&quot;&quot;,&quot;filter_cat_tax&quot;:null,&quot;show_all_filter&quot;:null,&quot;thumbnail_size&quot;:&quot;alpha-post-small&quot;,&quot;post_found_nothing&quot;:&quot;&quot;,&quot;posts_wrap_cls&quot;:&quot;&quot;,&quot;hover_full_image&quot;:null,&quot;is_related&quot;:false,&quot;item_animation&quot;:&quot;none&quot;,&quot;item_reveal_effect_color&quot;:null,&quot;item_animation_duration&quot;:null,&quot;item_animation_delay&quot;:null},&quot;args&quot;:{&quot;post_status&quot;:&quot;publish&quot;,&quot;post_type&quot;:&quot;udesign_portfolio&quot;,&quot;posts_per_page&quot;:6,&quot;tax_query&quot;:[{&quot;taxonomy&quot;:&quot;udesign_portfolio_category&quot;,&quot;field&quot;:&quot;term_id&quot;,&quot;terms&quot;:[&quot;65&quot;,&quot;35&quot;,&quot;56&quot;]}],&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;DESC&quot;,&quot;cpt&quot;:&quot;portfolio&quot;},&quot;max&quot;:2}\" data-post-type=\"card\"><div class=\"alpha-tb-item udesign_portfolio post-12122 type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-documentos-en udesign_portfolio_category-documentos udesign_portfolio_category-ultimos-documentos-en udesign_portfolio_category-ultimos-documentos\">\r\n<div class=\"post-wrap \" data-post-image=\"alpha-post-small\">\r\n\r\n\t\r\n\t<article class=\"post-12122 udesign_portfolio type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-documentos-en udesign_portfolio_category-documentos udesign_portfolio_category-ultimos-documentos-en udesign_portfolio_category-ultimos-documentos rollover-container post  portfolio-card\">\r\n\t\t\t\t\t<figure class=\"post-media\">\r\n\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"280\" src=\"https:\/\/aniu.org.uy\/wp-content\/uploads\/2026\/07\/la-educacion-en-matematica-analisis-y-propuestas-julio-fernandez-400x280.jpg\" class=\"attachment-alpha-post-small size-alpha-post-small wp-post-image\" alt=\"La educaci\u00f3n en matem\u00e1tica: an\u00e1lisis y propuestas\" \/><div class=\"rollover\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/mathematics-education-analysis-and-proposals\/\" aria-label=\"Visit\" class=\"rollover-link-wrapper\"><\/a><div class=\"rollover-content\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/mathematics-education-analysis-and-proposals\/\" class=\"rollover-link-wrapper\" aria-label=\"Rollover Link\"><\/a><\/div><\/div>\t\t\t<\/figure>\r\n\t\t\t<div class=\"post-details\">\r\n\t<div class=\"post-cats\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos_cat\/documentos-en\/\" rel=\"tag\">Documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/documentos_cat\/documentos\/\" rel=\"tag\">Documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/en\/documentos_cat\/ultimos-documentos-en\/\" rel=\"tag\">\u00daltimos documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/documentos_cat\/ultimos-documentos\/\" rel=\"tag\">\u00daltimos documentos<\/a><\/div><h3 class=\"post-title\">\r\n\t<a href=\"https:\/\/aniu.org.uy\/en\/documentos\/mathematics-education-analysis-and-proposals\/\">\r\n\t\tMathematics Education: Analysis and Proposals\t<\/a>\r\n<\/h3>\r\n<\/div>\r\n\t<\/article>\r\n\r\n\t\r\n<\/div>\r\n\r\n<\/div><div class=\"alpha-tb-item udesign_portfolio post-12008 type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-documentos-en udesign_portfolio_category-documentos udesign_portfolio_category-ultimos-documentos-en udesign_portfolio_category-ultimos-documentos\">\r\n<div class=\"post-wrap \" data-post-image=\"alpha-post-small\">\r\n\r\n\t\r\n\t<article class=\"post-12008 udesign_portfolio type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-documentos-en udesign_portfolio_category-documentos udesign_portfolio_category-ultimos-documentos-en udesign_portfolio_category-ultimos-documentos rollover-container post  portfolio-card\">\r\n\t\t\t\t\t<figure class=\"post-media\">\r\n\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"280\" src=\"https:\/\/aniu.org.uy\/wp-content\/uploads\/2026\/02\/ensenanza-de-la-matematica-en-uruguay-algunas-reflexiones-400x280.jpg\" class=\"attachment-alpha-post-small size-alpha-post-small wp-post-image\" alt=\"Ense\u00f1anza de la Matem\u00e1tica en Uruguay: algunas reflexiones\" \/><div class=\"rollover\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/mathematics-education-in-uruguay-some-reflections\/\" aria-label=\"Visit\" class=\"rollover-link-wrapper\"><\/a><div class=\"rollover-content\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/mathematics-education-in-uruguay-some-reflections\/\" class=\"rollover-link-wrapper\" aria-label=\"Rollover Link\"><\/a><\/div><\/div>\t\t\t<\/figure>\r\n\t\t\t<div class=\"post-details\">\r\n\t<div class=\"post-cats\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos_cat\/documentos-en\/\" rel=\"tag\">Documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/documentos_cat\/documentos\/\" rel=\"tag\">Documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/en\/documentos_cat\/ultimos-documentos-en\/\" rel=\"tag\">\u00daltimos documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/documentos_cat\/ultimos-documentos\/\" rel=\"tag\">\u00daltimos documentos<\/a><\/div><h3 class=\"post-title\">\r\n\t<a href=\"https:\/\/aniu.org.uy\/en\/documentos\/mathematics-education-in-uruguay-some-reflections\/\">\r\n\t\tMathematics education in Uruguay: some reflections\t<\/a>\r\n<\/h3>\r\n<\/div>\r\n\t<\/article>\r\n\r\n\t\r\n<\/div>\r\n\r\n<\/div><div class=\"alpha-tb-item udesign_portfolio post-11667 type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-ultimos-documentos\">\r\n<div class=\"post-wrap \" data-post-image=\"alpha-post-small\">\r\n\r\n\t\r\n\t<article class=\"post-11667 udesign_portfolio type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-ultimos-documentos rollover-container post  portfolio-card\">\r\n\t\t\t\t\t<figure class=\"post-media\">\r\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"280\" src=\"https:\/\/aniu.org.uy\/wp-content\/uploads\/2025\/02\/articulo-el-cambio-climatico-y-su-impacto-en-uruguay-400x280.jpg\" class=\"attachment-alpha-post-small size-alpha-post-small wp-post-image\" alt=\"Notas sobre el Cambio de Clima, Extremos Clim\u00e1ticos y Adaptaci\u00f3n con Referencia a Uruguay\" \/><div class=\"rollover\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/notas-sobre-el-cambio-de-clima-extremos-climaticos-y-adaptacion-con-referencia-a-uruguay\/\" aria-label=\"Visit\" class=\"rollover-link-wrapper\"><\/a><div class=\"rollover-content\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/notas-sobre-el-cambio-de-clima-extremos-climaticos-y-adaptacion-con-referencia-a-uruguay\/\" class=\"rollover-link-wrapper\" aria-label=\"Rollover Link\"><\/a><\/div><\/div>\t\t\t<\/figure>\r\n\t\t\t<div class=\"post-details\">\r\n\t<div class=\"post-cats\"><a href=\"https:\/\/aniu.org.uy\/documentos_cat\/ultimos-documentos\/\" rel=\"tag\">\u00daltimos documentos<\/a><\/div><h3 class=\"post-title\">\r\n\t<a href=\"https:\/\/aniu.org.uy\/en\/documentos\/notas-sobre-el-cambio-de-clima-extremos-climaticos-y-adaptacion-con-referencia-a-uruguay\/\">\r\n\t\tNotas sobre el Cambio de Clima, Extremos Clim\u00e1ticos y Adaptaci\u00f3n con Referencia a Uruguay\t<\/a>\r\n<\/h3>\r\n<\/div>\r\n\t<\/article>\r\n\r\n\t\r\n<\/div>\r\n\r\n<\/div><div class=\"alpha-tb-item udesign_portfolio post-11266 type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-documentos-en udesign_portfolio_category-documentos udesign_portfolio_category-ultimos-documentos-en udesign_portfolio_category-ultimos-documentos\">\r\n<div class=\"post-wrap \" data-post-image=\"alpha-post-small\">\r\n\r\n\t\r\n\t<article class=\"post-11266 udesign_portfolio type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-documentos-en udesign_portfolio_category-documentos udesign_portfolio_category-ultimos-documentos-en udesign_portfolio_category-ultimos-documentos rollover-container post  portfolio-card\">\r\n\t\t\t\t\t<figure class=\"post-media\">\r\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"280\" src=\"https:\/\/aniu.org.uy\/wp-content\/uploads\/2023\/08\/resumen-final-del-proyecto-sobre-education-stem-en-uruguay_documento-400x280.jpg\" class=\"attachment-alpha-post-small size-alpha-post-small wp-post-image\" alt=\"La educaci\u00f3n STEM en Uruguay: Desaf\u00edo de todos - Resumen consolidado final\" \/><div class=\"rollover\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/la-educacion-stem-en-uruguay-desafio-de-todos-resumen-consolidado-final\/\" aria-label=\"Visit\" class=\"rollover-link-wrapper\"><\/a><div class=\"rollover-content\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/la-educacion-stem-en-uruguay-desafio-de-todos-resumen-consolidado-final\/\" class=\"rollover-link-wrapper\" aria-label=\"Rollover Link\"><\/a><\/div><\/div>\t\t\t<\/figure>\r\n\t\t\t<div class=\"post-details\">\r\n\t<div class=\"post-cats\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos_cat\/documentos-en\/\" rel=\"tag\">Documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/documentos_cat\/documentos\/\" rel=\"tag\">Documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/en\/documentos_cat\/ultimos-documentos-en\/\" rel=\"tag\">\u00daltimos documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/documentos_cat\/ultimos-documentos\/\" rel=\"tag\">\u00daltimos documentos<\/a><\/div><h3 class=\"post-title\">\r\n\t<a href=\"https:\/\/aniu.org.uy\/en\/documentos\/la-educacion-stem-en-uruguay-desafio-de-todos-resumen-consolidado-final\/\">\r\n\t\tLa educaci\u00f3n STEM en Uruguay: Desaf\u00edo de todos \u2013 Resumen consolidado final\t<\/a>\r\n<\/h3>\r\n<\/div>\r\n\t<\/article>\r\n\r\n\t\r\n<\/div>\r\n\r\n<\/div><div class=\"alpha-tb-item udesign_portfolio post-11272 type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-documentos-en udesign_portfolio_category-documentos udesign_portfolio_category-ultimos-documentos-en udesign_portfolio_category-ultimos-documentos\">\r\n<div class=\"post-wrap \" data-post-image=\"alpha-post-small\">\r\n\r\n\t\r\n\t<article class=\"post-11272 udesign_portfolio type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-documentos-en udesign_portfolio_category-documentos udesign_portfolio_category-ultimos-documentos-en udesign_portfolio_category-ultimos-documentos rollover-container post  portfolio-card\">\r\n\t\t\t\t\t<figure class=\"post-media\">\r\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"280\" src=\"https:\/\/aniu.org.uy\/wp-content\/uploads\/2023\/08\/informe-final-de-la-segunda-etapa-del-proyecto-education-stem-en-uruguay_documento-400x280.jpg\" class=\"attachment-alpha-post-small size-alpha-post-small wp-post-image\" alt=\"La educaci\u00f3n STEM en Uruguay: Desaf\u00edo de todos - Segunda etapa: Entrevistas y Propuestas (Informe final)\" \/><div class=\"rollover\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/la-educacion-stem-en-uruguay-desafio-de-todos-segunda-etapa-entrevistas-y-propuestas-informe-final\/\" aria-label=\"Visit\" class=\"rollover-link-wrapper\"><\/a><div class=\"rollover-content\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/la-educacion-stem-en-uruguay-desafio-de-todos-segunda-etapa-entrevistas-y-propuestas-informe-final\/\" class=\"rollover-link-wrapper\" aria-label=\"Rollover Link\"><\/a><\/div><\/div>\t\t\t<\/figure>\r\n\t\t\t<div class=\"post-details\">\r\n\t<div class=\"post-cats\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos_cat\/documentos-en\/\" rel=\"tag\">Documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/documentos_cat\/documentos\/\" rel=\"tag\">Documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/en\/documentos_cat\/ultimos-documentos-en\/\" rel=\"tag\">\u00daltimos documentos<\/a>, <a href=\"https:\/\/aniu.org.uy\/documentos_cat\/ultimos-documentos\/\" rel=\"tag\">\u00daltimos documentos<\/a><\/div><h3 class=\"post-title\">\r\n\t<a href=\"https:\/\/aniu.org.uy\/en\/documentos\/la-educacion-stem-en-uruguay-desafio-de-todos-segunda-etapa-entrevistas-y-propuestas-informe-final\/\">\r\n\t\tLa educaci\u00f3n STEM en Uruguay: Desaf\u00edo de todos \u2013 Segunda etapa: Entrevistas y Propuestas (Informe final)\t<\/a>\r\n<\/h3>\r\n<\/div>\r\n\t<\/article>\r\n\r\n\t\r\n<\/div>\r\n\r\n<\/div><div class=\"alpha-tb-item udesign_portfolio post-10128 type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-documentos\">\r\n<div class=\"post-wrap \" data-post-image=\"alpha-post-small\">\r\n\r\n\t\r\n\t<article class=\"post-10128 udesign_portfolio type-udesign_portfolio status-publish has-post-thumbnail hentry udesign_portfolio_category-documentos rollover-container post  portfolio-card\">\r\n\t\t\t\t\t<figure class=\"post-media\">\r\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"280\" src=\"https:\/\/aniu.org.uy\/wp-content\/uploads\/2023\/03\/estatutos-y-reglamentos-de-la-academia-nacional-de-ingenieria-400x280.jpg\" class=\"attachment-alpha-post-small size-alpha-post-small wp-post-image\" alt=\"\" \/><div class=\"rollover\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/statutes-and-bylaws-of-the-national-academy-of-engineering\/\" aria-label=\"Visit\" class=\"rollover-link-wrapper\"><\/a><div class=\"rollover-content\"><a href=\"https:\/\/aniu.org.uy\/en\/documentos\/statutes-and-bylaws-of-the-national-academy-of-engineering\/\" class=\"rollover-link-wrapper\" aria-label=\"Rollover Link\"><\/a><\/div><\/div>\t\t\t<\/figure>\r\n\t\t\t<div class=\"post-details\">\r\n\t<div class=\"post-cats\"><a href=\"https:\/\/aniu.org.uy\/documentos_cat\/documentos\/\" rel=\"tag\">Documentos<\/a><\/div><h3 class=\"post-title\">\r\n\t<a href=\"https:\/\/aniu.org.uy\/en\/documentos\/statutes-and-bylaws-of-the-national-academy-of-engineering\/\">\r\n\t\tStatutes and Bylaws of the National Academy of Engineering\t<\/a>\r\n<\/h3>\r\n<\/div>\r\n\t<\/article>\r\n\r\n\t\r\n<\/div>\r\n\r\n<\/div><\/div><button class=\"btn btn-load btn-primary btn-outline btn-md\">Load more<\/button><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<section class=\" elementor-section elementor-top-section elementor-element elementor-element-07862eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"07862eb\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\" elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5e3293 \" data-id=\"e5e3293\" data-element_type=\"column\" data-e-type=\"column\">\r\n\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcfb3c2 elementor-widget elementor-widget-spacer\" data-id=\"dcfb3c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/section>\r\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Todos All documents Home \u00daltimos documentos Producci\u00f3n forestal en el Uruguay: balance y perspectivas Documentos Historia de un Eldorado \u2013 Conferencia de Juan Villena \u00daltimos documentos Competencias y criterios internacionales para carreras de ingenier\u00eda Documentos Acto de recepci\u00f3n de nuevos acad\u00e9micos y entrega de premios 2015 Documentos, \u00daltimos documentos Mesa redonda: Ciberseguridad \u2013 perspectivas y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-9841","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Todos All documents Home&gt;All documents Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics Education: Analysis and Proposals Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics education in Uruguay: some reflections \u00daltimos documentos Notas sobre el Cambio de Clima, Extremos Clim\u00e1ticos y Adaptaci\u00f3n con Referencia a Uruguay Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos La educaci\u00f3n STEM en Uruguay:\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/aniu.org.uy\/en\/all-documents\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Academia Nacional de Ingenier\u00eda del Uruguay - ANIU\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"All documents - Academia Nacional de Ingenier\u00eda del Uruguay\" \/>\n\t\t<meta property=\"og:description\" content=\"Todos All documents Home&gt;All documents Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics Education: Analysis and Proposals Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics education in Uruguay: some reflections \u00daltimos documentos Notas sobre el Cambio de Clima, Extremos Clim\u00e1ticos y Adaptaci\u00f3n con Referencia a Uruguay Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos La educaci\u00f3n STEM en Uruguay:\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/aniu.org.uy\/en\/all-documents\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/aniu.org.uy\/wp-content\/uploads\/2022\/12\/cropped-logo-aniu-web.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/aniu.org.uy\/wp-content\/uploads\/2022\/12\/cropped-logo-aniu-web.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-04-14T12:18:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-05T19:39:05+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"All documents - Academia Nacional de Ingenier\u00eda del Uruguay\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Todos All documents Home&gt;All documents Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics Education: Analysis and Proposals Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics education in Uruguay: some reflections \u00daltimos documentos Notas sobre el Cambio de Clima, Extremos Clim\u00e1ticos y Adaptaci\u00f3n con Referencia a Uruguay Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos La educaci\u00f3n STEM en Uruguay:\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/aniu.org.uy\/wp-content\/uploads\/2022\/12\/cropped-logo-aniu-web.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/all-documents\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/all-documents\\\/#listItem\",\"name\":\"All documents\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/all-documents\\\/#listItem\",\"position\":2,\"name\":\"All documents\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/#organization\",\"name\":\"Academia Nacional de Ingenier\\u00eda del Uruguay\",\"description\":\"ANIU\",\"url\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/\",\"telephone\":\"+59829011762\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/aniu.org.uy\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/cropped-logo-aniu-web.png\",\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/all-documents\\\/#organizationLogo\",\"width\":900,\"height\":170},\"image\":{\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/all-documents\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/all-documents\\\/#webpage\",\"url\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/all-documents\\\/\",\"name\":\"All documents - Academia Nacional de Ingenier\\u00eda del Uruguay\",\"description\":\"Todos All documents Home>All documents Documentos, Documentos, \\u00daltimos documentos, \\u00daltimos documentos Mathematics Education: Analysis and Proposals Documentos, Documentos, \\u00daltimos documentos, \\u00daltimos documentos Mathematics education in Uruguay: some reflections \\u00daltimos documentos Notas sobre el Cambio de Clima, Extremos Clim\\u00e1ticos y Adaptaci\\u00f3n con Referencia a Uruguay Documentos, Documentos, \\u00daltimos documentos, \\u00daltimos documentos La educaci\\u00f3n STEM en Uruguay:\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/all-documents\\\/#breadcrumblist\"},\"datePublished\":\"2023-04-14T09:18:15-03:00\",\"dateModified\":\"2023-05-05T16:39:05-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/\",\"name\":\"Academia Nacional de Ingenier\\u00eda del Uruguay\",\"description\":\"ANIU\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/aniu.org.uy\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"All documents - Academia Nacional de Ingenier\u00eda del Uruguay","description":"Todos All documents Home>All documents Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics Education: Analysis and Proposals Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics education in Uruguay: some reflections \u00daltimos documentos Notas sobre el Cambio de Clima, Extremos Clim\u00e1ticos y Adaptaci\u00f3n con Referencia a Uruguay Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos La educaci\u00f3n STEM en Uruguay:","canonical_url":"https:\/\/aniu.org.uy\/en\/all-documents\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/aniu.org.uy\/en\/all-documents\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/aniu.org.uy\/en\/#listItem","position":1,"name":"Inicio","item":"https:\/\/aniu.org.uy\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/aniu.org.uy\/en\/all-documents\/#listItem","name":"All documents"}},{"@type":"ListItem","@id":"https:\/\/aniu.org.uy\/en\/all-documents\/#listItem","position":2,"name":"All documents","previousItem":{"@type":"ListItem","@id":"https:\/\/aniu.org.uy\/en\/#listItem","name":"Inicio"}}]},{"@type":"Organization","@id":"https:\/\/aniu.org.uy\/en\/#organization","name":"Academia Nacional de Ingenier\u00eda del Uruguay","description":"ANIU","url":"https:\/\/aniu.org.uy\/en\/","telephone":"+59829011762","logo":{"@type":"ImageObject","url":"https:\/\/aniu.org.uy\/wp-content\/uploads\/2022\/12\/cropped-logo-aniu-web.png","@id":"https:\/\/aniu.org.uy\/en\/all-documents\/#organizationLogo","width":900,"height":170},"image":{"@id":"https:\/\/aniu.org.uy\/en\/all-documents\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/aniu.org.uy\/en\/all-documents\/#webpage","url":"https:\/\/aniu.org.uy\/en\/all-documents\/","name":"All documents - Academia Nacional de Ingenier\u00eda del Uruguay","description":"Todos All documents Home>All documents Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics Education: Analysis and Proposals Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics education in Uruguay: some reflections \u00daltimos documentos Notas sobre el Cambio de Clima, Extremos Clim\u00e1ticos y Adaptaci\u00f3n con Referencia a Uruguay Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos La educaci\u00f3n STEM en Uruguay:","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/aniu.org.uy\/en\/#website"},"breadcrumb":{"@id":"https:\/\/aniu.org.uy\/en\/all-documents\/#breadcrumblist"},"datePublished":"2023-04-14T09:18:15-03:00","dateModified":"2023-05-05T16:39:05-03:00"},{"@type":"WebSite","@id":"https:\/\/aniu.org.uy\/en\/#website","url":"https:\/\/aniu.org.uy\/en\/","name":"Academia Nacional de Ingenier\u00eda del Uruguay","description":"ANIU","inLanguage":"en-US","publisher":{"@id":"https:\/\/aniu.org.uy\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Academia Nacional de Ingenier\u00eda del Uruguay - ANIU","og:type":"article","og:title":"All documents - Academia Nacional de Ingenier\u00eda del Uruguay","og:description":"Todos All documents Home&gt;All documents Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics Education: Analysis and Proposals Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics education in Uruguay: some reflections \u00daltimos documentos Notas sobre el Cambio de Clima, Extremos Clim\u00e1ticos y Adaptaci\u00f3n con Referencia a Uruguay Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos La educaci\u00f3n STEM en Uruguay:","og:url":"https:\/\/aniu.org.uy\/en\/all-documents\/","og:image":"https:\/\/aniu.org.uy\/wp-content\/uploads\/2022\/12\/cropped-logo-aniu-web.png","og:image:secure_url":"https:\/\/aniu.org.uy\/wp-content\/uploads\/2022\/12\/cropped-logo-aniu-web.png","article:published_time":"2023-04-14T12:18:15+00:00","article:modified_time":"2023-05-05T19:39:05+00:00","twitter:card":"summary_large_image","twitter:title":"All documents - Academia Nacional de Ingenier\u00eda del Uruguay","twitter:description":"Todos All documents Home&gt;All documents Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics Education: Analysis and Proposals Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos Mathematics education in Uruguay: some reflections \u00daltimos documentos Notas sobre el Cambio de Clima, Extremos Clim\u00e1ticos y Adaptaci\u00f3n con Referencia a Uruguay Documentos, Documentos, \u00daltimos documentos, \u00daltimos documentos La educaci\u00f3n STEM en Uruguay:","twitter:image":"https:\/\/aniu.org.uy\/wp-content\/uploads\/2022\/12\/cropped-logo-aniu-web.png"},"aioseo_meta_data":{"post_id":"9841","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-05 17:59:03","updated":"2025-06-23 21:15:51","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/aniu.org.uy\/en\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAll documents\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/aniu.org.uy\/en\/"},{"label":"All documents","link":"https:\/\/aniu.org.uy\/en\/all-documents\/"}],"_links":{"self":[{"href":"https:\/\/aniu.org.uy\/en\/wp-json\/wp\/v2\/pages\/9841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aniu.org.uy\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aniu.org.uy\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aniu.org.uy\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aniu.org.uy\/en\/wp-json\/wp\/v2\/comments?post=9841"}],"version-history":[{"count":0,"href":"https:\/\/aniu.org.uy\/en\/wp-json\/wp\/v2\/pages\/9841\/revisions"}],"wp:attachment":[{"href":"https:\/\/aniu.org.uy\/en\/wp-json\/wp\/v2\/media?parent=9841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}